{"id":10023,"date":"2023-12-13T08:00:00","date_gmt":"2023-12-13T07:00:00","guid":{"rendered":"http:\/\/www.blog.neoprog.eu\/?p=10023"},"modified":"2023-12-12T17:28:00","modified_gmt":"2023-12-12T16:28:00","slug":"la-poupee","status":"publish","type":"post","link":"https:\/\/www.blog.neoprog.eu\/index.php\/2023\/12\/13\/la-poupee\/","title":{"rendered":"La poup\u00e9e"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"885\" height=\"500\" src=\"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2023\/12\/la-poupee.jpeg\" alt=\"\" class=\"wp-image-10024\" srcset=\"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2023\/12\/la-poupee.jpeg 885w, https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2023\/12\/la-poupee-300x169.jpeg 300w, https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2023\/12\/la-poupee-768x434.jpeg 768w, https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2023\/12\/la-poupee-500x282.jpeg 500w\" sizes=\"auto, (max-width: 885px) 100vw, 885px\" \/><\/figure>\n\n\n\n<p>J\u2019avais d\u00e9j\u00e0 lu <a href=\"https:\/\/www.blog.neoprog.eu\/index.php\/2022\/04\/20\/le-trou\/\">un roman de Yrsa Sigurdardottir<\/a> il y a quelques temps et il ne m\u2019avait pas emball\u00e9. Mais comme j\u2019ai la m\u00e9moire courte et que je suis accro aux polars islandais, j\u2019ai lu la suite sans le savoir. Et le pire dans tout \u00e7a, c\u2019est que je l\u2019ai bien aim\u00e9.<\/p>\n\n\n\n<p>Une poup\u00e9e rest\u00e9e longtemps fond de l\u2019oc\u00e9an est ramass\u00e9e dans un filet par un p\u00eacheur du dimanche. Un objet hideux et puant recouvert de mollusques qui devient le coeur d\u2019une enqu\u00eate polici\u00e8re.<\/p>\n\n\n\n<p>Une enqu\u00eate ? Non plut\u00f4t quatre, deux meurtres, des ossements retrouv\u00e9s et des accusations pour abus sexuels sur mineurs.<\/p>\n\n\n\n<p>Dans cette nouvelle histoire, on retrouve les protagonistes du pr\u00e9c\u00e9dent roman Le Trou, Huldar, Lina et Freyja qui n\u2019ont pas gagn\u00e9 vraiment en \u00e9paisseur. Cependant l\u2019autrice nous plonge dans des enqu\u00eates passionnantes, dans l\u2019univers des services sociaux d\u2019Islande et le monde de la drogue.<\/p>\n\n\n\n<p>Tr\u00e8s vite on s\u2019attache \u00e0 Rosa et Tristan, deux ados plac\u00e9s en foyers o\u00f9 un \u00e9ducateur aurait abus\u00e9 d\u2019eux. Une nouvelle occasion pour le policier Huldar de se rapprocher de Freyja, la jeune femme des services sociaux.<\/p>\n\n\n\n<p>C\u2019est l\u2019\u00e9t\u00e9 en Islande, un \u00e9t\u00e9 pourri. Tous les policiers sont partis en vacances bronzer plus au sud. Avec quatre enqu\u00eates diff\u00e9rentes, des sous effectifs en pagaille, Huldar ne va pas ch\u00f4mer. Quel peut-\u00eatre le lien entre une poup\u00e9e hideuse, un SDF \u00e9gorg\u00e9, deux ados plac\u00e9s et des squelettes perdus en mer ?&nbsp;<\/p>\n\n\n\n<p>L\u2019intrigue m\u2019a passionn\u00e9, alors que d\u2019ordinaire je m\u2019int\u00e9resse plus aux personnages et aux ambiances. Dommage que l\u2019avant dernier chapitre, celui qui recolle quelques parties du puzzle, soit un peu b\u00e2cl\u00e9. \u00c7a aurait donn\u00e9 un fabuleux polar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>J\u2019avais d\u00e9j\u00e0 lu un roman de Yrsa Sigurdardottir il y a quelques temps et il ne m\u2019avait pas emball\u00e9.  <a href=\"https:\/\/www.blog.neoprog.eu\/index.php\/2023\/12\/13\/la-poupee\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":10024,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[5],"tags":[2452,1444,3046,1441,203,2432],"class_list":["post-10023","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-livre","tag-actes-sud","tag-islande","tag-la-poupee","tag-policier","tag-roman","tag-yrsa-sigurdardottir","post_format-post-format-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La poup\u00e9e - Le Blog du N\u00e9oprog<\/title>\n<meta name=\"description\" content=\"J\u2019avais d\u00e9j\u00e0 lu un roman de Yrsa Sigurdardottir il y a quelques temps et il ne m\u2019avait pas emball\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.blog.neoprog.eu\/index.php\/2023\/12\/13\/la-poupee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La poup\u00e9e - Le Blog du N\u00e9oprog\" \/>\n<meta property=\"og:description\" content=\"J\u2019avais d\u00e9j\u00e0 lu un roman de Yrsa Sigurdardottir il y a quelques temps et il ne m\u2019avait pas emball\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blog.neoprog.eu\/index.php\/2023\/12\/13\/la-poupee\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Blog du N\u00e9oprog\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-13T07:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2023\/12\/la-poupee.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"885\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Neoprog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Le_Brun_JC\" \/>\n<meta name=\"twitter:site\" content=\"@Le_Brun_JC\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Neoprog\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2023\\\/12\\\/13\\\/la-poupee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2023\\\/12\\\/13\\\/la-poupee\\\/\"},\"author\":{\"name\":\"Neoprog\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#\\\/schema\\\/person\\\/47c594bf12736b172b772f0f02bcf511\"},\"headline\":\"La poup\u00e9e\",\"datePublished\":\"2023-12-13T07:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2023\\\/12\\\/13\\\/la-poupee\\\/\"},\"wordCount\":320,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#\\\/schema\\\/person\\\/47c594bf12736b172b772f0f02bcf511\"},\"image\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2023\\\/12\\\/13\\\/la-poupee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/la-poupee.jpeg\",\"keywords\":[\"Actes Sud\",\"Islande\",\"La Poup\u00e9e\",\"policier\",\"roman\",\"Yrsa Sigurdardottir\"],\"articleSection\":[\"Livres\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2023\\\/12\\\/13\\\/la-poupee\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2023\\\/12\\\/13\\\/la-poupee\\\/\",\"url\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2023\\\/12\\\/13\\\/la-poupee\\\/\",\"name\":\"La poup\u00e9e - Le Blog du N\u00e9oprog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2023\\\/12\\\/13\\\/la-poupee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2023\\\/12\\\/13\\\/la-poupee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/la-poupee.jpeg\",\"datePublished\":\"2023-12-13T07:00:00+00:00\",\"description\":\"J\u2019avais d\u00e9j\u00e0 lu un roman de Yrsa Sigurdardottir il y a quelques temps et il ne m\u2019avait pas emball\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2023\\\/12\\\/13\\\/la-poupee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2023\\\/12\\\/13\\\/la-poupee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2023\\\/12\\\/13\\\/la-poupee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/la-poupee.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/la-poupee.jpeg\",\"width\":885,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2023\\\/12\\\/13\\\/la-poupee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La poup\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/\",\"name\":\"Le Blog du N\u00e9oprog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#\\\/schema\\\/person\\\/47c594bf12736b172b772f0f02bcf511\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#\\\/schema\\\/person\\\/47c594bf12736b172b772f0f02bcf511\",\"name\":\"Neoprog\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/autoportrait-2.jpg\",\"url\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/autoportrait-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/autoportrait-2.jpg\",\"width\":1024,\"height\":681,\"caption\":\"Neoprog\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/autoportrait-2.jpg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La poup\u00e9e - Le Blog du N\u00e9oprog","description":"J\u2019avais d\u00e9j\u00e0 lu un roman de Yrsa Sigurdardottir il y a quelques temps et il ne m\u2019avait pas emball\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.blog.neoprog.eu\/index.php\/2023\/12\/13\/la-poupee\/","og_locale":"fr_FR","og_type":"article","og_title":"La poup\u00e9e - Le Blog du N\u00e9oprog","og_description":"J\u2019avais d\u00e9j\u00e0 lu un roman de Yrsa Sigurdardottir il y a quelques temps et il ne m\u2019avait pas emball\u00e9.","og_url":"https:\/\/www.blog.neoprog.eu\/index.php\/2023\/12\/13\/la-poupee\/","og_site_name":"Le Blog du N\u00e9oprog","article_published_time":"2023-12-13T07:00:00+00:00","og_image":[{"width":885,"height":500,"url":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2023\/12\/la-poupee.jpeg","type":"image\/jpeg"}],"author":"Neoprog","twitter_card":"summary_large_image","twitter_creator":"@Le_Brun_JC","twitter_site":"@Le_Brun_JC","twitter_misc":{"\u00c9crit par":"Neoprog","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2023\/12\/13\/la-poupee\/#article","isPartOf":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2023\/12\/13\/la-poupee\/"},"author":{"name":"Neoprog","@id":"https:\/\/www.blog.neoprog.eu\/#\/schema\/person\/47c594bf12736b172b772f0f02bcf511"},"headline":"La poup\u00e9e","datePublished":"2023-12-13T07:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2023\/12\/13\/la-poupee\/"},"wordCount":320,"commentCount":0,"publisher":{"@id":"https:\/\/www.blog.neoprog.eu\/#\/schema\/person\/47c594bf12736b172b772f0f02bcf511"},"image":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2023\/12\/13\/la-poupee\/#primaryimage"},"thumbnailUrl":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2023\/12\/la-poupee.jpeg","keywords":["Actes Sud","Islande","La Poup\u00e9e","policier","roman","Yrsa Sigurdardottir"],"articleSection":["Livres"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.blog.neoprog.eu\/index.php\/2023\/12\/13\/la-poupee\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2023\/12\/13\/la-poupee\/","url":"https:\/\/www.blog.neoprog.eu\/index.php\/2023\/12\/13\/la-poupee\/","name":"La poup\u00e9e - Le Blog du N\u00e9oprog","isPartOf":{"@id":"https:\/\/www.blog.neoprog.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2023\/12\/13\/la-poupee\/#primaryimage"},"image":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2023\/12\/13\/la-poupee\/#primaryimage"},"thumbnailUrl":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2023\/12\/la-poupee.jpeg","datePublished":"2023-12-13T07:00:00+00:00","description":"J\u2019avais d\u00e9j\u00e0 lu un roman de Yrsa Sigurdardottir il y a quelques temps et il ne m\u2019avait pas emball\u00e9.","breadcrumb":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2023\/12\/13\/la-poupee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blog.neoprog.eu\/index.php\/2023\/12\/13\/la-poupee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2023\/12\/13\/la-poupee\/#primaryimage","url":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2023\/12\/la-poupee.jpeg","contentUrl":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2023\/12\/la-poupee.jpeg","width":885,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2023\/12\/13\/la-poupee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.blog.neoprog.eu\/"},{"@type":"ListItem","position":2,"name":"La poup\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/www.blog.neoprog.eu\/#website","url":"https:\/\/www.blog.neoprog.eu\/","name":"Le Blog du N\u00e9oprog","description":"","publisher":{"@id":"https:\/\/www.blog.neoprog.eu\/#\/schema\/person\/47c594bf12736b172b772f0f02bcf511"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blog.neoprog.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.blog.neoprog.eu\/#\/schema\/person\/47c594bf12736b172b772f0f02bcf511","name":"Neoprog","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2022\/09\/autoportrait-2.jpg","url":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2022\/09\/autoportrait-2.jpg","contentUrl":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2022\/09\/autoportrait-2.jpg","width":1024,"height":681,"caption":"Neoprog"},"logo":{"@id":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2022\/09\/autoportrait-2.jpg"}}]}},"_links":{"self":[{"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/posts\/10023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/comments?post=10023"}],"version-history":[{"count":2,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/posts\/10023\/revisions"}],"predecessor-version":[{"id":10034,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/posts\/10023\/revisions\/10034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/media\/10024"}],"wp:attachment":[{"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/media?parent=10023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/categories?post=10023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/tags?post=10023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}