{"id":11171,"date":"2025-01-10T08:00:00","date_gmt":"2025-01-10T07:00:00","guid":{"rendered":"https:\/\/www.blog.neoprog.eu\/?p=11171"},"modified":"2025-01-02T17:18:47","modified_gmt":"2025-01-02T16:18:47","slug":"la-petite-fille-sous-la-neige","status":"publish","type":"post","link":"https:\/\/www.blog.neoprog.eu\/index.php\/2025\/01\/10\/la-petite-fille-sous-la-neige\/","title":{"rendered":"La petite fille sous la neige"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2025\/01\/la-petite-fille-sous-la-neige-1024x576.jpeg\" alt=\"\" class=\"wp-image-11172\" srcset=\"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2025\/01\/la-petite-fille-sous-la-neige-1024x576.jpeg 1024w, https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2025\/01\/la-petite-fille-sous-la-neige-300x169.jpeg 300w, https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2025\/01\/la-petite-fille-sous-la-neige-768x432.jpeg 768w, https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2025\/01\/la-petite-fille-sous-la-neige-500x281.jpeg 500w, https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2025\/01\/la-petite-fille-sous-la-neige.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Mise en garde : j\u2019ai commenc\u00e9 ce roman un dimanche alors que j\u2019\u00e9tais en panne de livre. Ma librairie pr\u00e9f\u00e9r\u00e9e \u00e9tait ferm\u00e9e (mais que font les libraires le week-end ?) et que ce bouquin tra\u00eenait dans notre biblioth\u00e8que.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u2019est certainement la phrase \u00ab\u00a0Le nouveau ph\u00e9nom\u00e8ne litt\u00e9raire.\u00a0\u00bb sign\u00e9e <a href=\"https:\/\/www.blog.neoprog.eu\/index.php\/2022\/08\/17\/laffaire-alaska-sanders\/\">Jo\u00ebl Dicker<\/a> en haut de la couverture qui a motiv\u00e9 son achat un jour d\u2019\u00e9garement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kiera Templeton, une petite fille de trois ans, dispara\u00eet lors de la grande parade de Thanksgiving \u00e0 New-York en 1998. Miren, une jeune \u00e9tudiante en journalisme, touch\u00e9e par le fait divers, se lance dans l\u2019enqu\u00eate et infatigable, la m\u00e8nera jusqu\u2019\u00e0 son terme douze ans plus tard.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le roman de Javier Castillo, salu\u00e9 par Jo\u00ebl Dicker dont il reprend un peu les codes, est une enqu\u00eate polici\u00e8re qui voyage dans le temps de 1998 jusqu\u2019en 2013, avec de multiples aller-retour et plusieurs r\u00e9cits parall\u00e8les.\u00a0Un artifice litt\u00e9raire qui permet au lecteur de ne pas s\u2019ennuyer alors que l\u2019histoire de cette disparition, expliqu\u00e9e assez rapidement dans le livre, ne poss\u00e8de rien d\u2019extraordinaire au final.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le roman s\u2019attache beaucoup \u00e0 la vie de la journaliste Miren ainsi qu\u2019\u00e0 ses traumas qui en ont fait d\u2019elle\u00a0 cette femme pugnace qui ne lache rien, m\u00eame une enqu\u00eate vieille de douze ans. Le style est efficace et le rythme soutenu, sans r\u00e9el temps mort \u00e0 la mani\u00e8re d\u2019un thriller. Un livre qui se lit vite mais qui s\u2019oublie tr\u00e8s rapidement. Ce n\u2019est pas La V\u00e9rit\u00e9 sur l\u2019Affaire Harry Quebert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u2019ai de nombreux reproches \u00e0 faire \u00e0 cette histoire block buster. Pourquoi un auteur espagnol transporte-t\u2019il son r\u00e9cit aux \u00c9tats Unis si ce n\u2019est pour mieux vendre ? Pourquoi fait-il \u00e9galement l\u2019apologie de l\u2019auto justice et de la d\u00e9tention d\u2019arme \u00e0 feu dans ce livre ? Certes l\u2019histoire se d\u00e9roule \u00e0 New-York, mais cela n\u2019excuse pas tout. Enfin, la tr\u00e8s longue captivit\u00e9 de la petite Kiera est clairement tir\u00e9e par les cheveux m\u00eame si l\u2019auteur use de quelques artifices pour la justifier.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un roman de gare tout au plus qui se lit tr\u00e8s vite mais qui ne m\u00e9rite pas forc\u00e9ment le temps pass\u00e9. Sauf si vous n\u2019avez plus rien \u00e0 lire bien s\u00fbr\u2026 Il a \u00e9t\u00e9 adapt\u00e9 en s\u00e9rie TV en 2023.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"706\" height=\"1024\" src=\"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2025\/01\/livre-706x1024.jpeg\" alt=\"\" class=\"wp-image-11173\" srcset=\"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2025\/01\/livre-706x1024.jpeg 706w, https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2025\/01\/livre-207x300.jpeg 207w, https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2025\/01\/livre-768x1114.jpeg 768w, https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2025\/01\/livre-1058x1536.jpeg 1058w, https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2025\/01\/livre-1411x2048.jpeg 1411w, https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2025\/01\/livre-scaled.jpeg 1764w\" sizes=\"auto, (max-width: 706px) 100vw, 706px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Kiera Templeton, une petite fille de trois ans, dispara\u00eet lors de la grande parade de Thanksgiving \u00e0 New-York en 1998. <a href=\"https:\/\/www.blog.neoprog.eu\/index.php\/2025\/01\/10\/la-petite-fille-sous-la-neige\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":11172,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[5],"tags":[3393,1043,3394,199,426],"class_list":["post-11171","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-livre","tag-javier-castillo","tag-joel-dicker","tag-la-petite-fille-sous-la-neige","tag-livre","tag-serie-tv","post_format-post-format-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La petite fille sous la neige - Le Blog du N\u00e9oprog<\/title>\n<meta name=\"description\" content=\"Kiera Templeton, une petite fille de trois ans, dispara\u00eet lors de la grande parade de Thanksgiving \u00e0 New-York en 1998.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.blog.neoprog.eu\/index.php\/2025\/01\/10\/la-petite-fille-sous-la-neige\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La petite fille sous la neige - Le Blog du N\u00e9oprog\" \/>\n<meta property=\"og:description\" content=\"Kiera Templeton, une petite fille de trois ans, dispara\u00eet lors de la grande parade de Thanksgiving \u00e0 New-York en 1998.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blog.neoprog.eu\/index.php\/2025\/01\/10\/la-petite-fille-sous-la-neige\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Blog du N\u00e9oprog\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-10T07:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2025\/01\/la-petite-fille-sous-la-neige.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Neoprog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Le_Brun_JC\" \/>\n<meta name=\"twitter:site\" content=\"@Le_Brun_JC\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Neoprog\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2025\\\/01\\\/10\\\/la-petite-fille-sous-la-neige\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2025\\\/01\\\/10\\\/la-petite-fille-sous-la-neige\\\/\"},\"author\":{\"name\":\"Neoprog\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#\\\/schema\\\/person\\\/47c594bf12736b172b772f0f02bcf511\"},\"headline\":\"La petite fille sous la neige\",\"datePublished\":\"2025-01-10T07:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2025\\\/01\\\/10\\\/la-petite-fille-sous-la-neige\\\/\"},\"wordCount\":423,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#\\\/schema\\\/person\\\/47c594bf12736b172b772f0f02bcf511\"},\"image\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2025\\\/01\\\/10\\\/la-petite-fille-sous-la-neige\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/la-petite-fille-sous-la-neige.jpeg\",\"keywords\":[\"Javier Castillo\",\"Jo\u00ebl Dicker\",\"La petite fille sous la neige\",\"livre\",\"S\u00e9rie TV\"],\"articleSection\":[\"Livres\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2025\\\/01\\\/10\\\/la-petite-fille-sous-la-neige\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2025\\\/01\\\/10\\\/la-petite-fille-sous-la-neige\\\/\",\"url\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2025\\\/01\\\/10\\\/la-petite-fille-sous-la-neige\\\/\",\"name\":\"La petite fille sous la neige - Le Blog du N\u00e9oprog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2025\\\/01\\\/10\\\/la-petite-fille-sous-la-neige\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2025\\\/01\\\/10\\\/la-petite-fille-sous-la-neige\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/la-petite-fille-sous-la-neige.jpeg\",\"datePublished\":\"2025-01-10T07:00:00+00:00\",\"description\":\"Kiera Templeton, une petite fille de trois ans, dispara\u00eet lors de la grande parade de Thanksgiving \u00e0 New-York en 1998.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2025\\\/01\\\/10\\\/la-petite-fille-sous-la-neige\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2025\\\/01\\\/10\\\/la-petite-fille-sous-la-neige\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2025\\\/01\\\/10\\\/la-petite-fille-sous-la-neige\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/la-petite-fille-sous-la-neige.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/la-petite-fille-sous-la-neige.jpeg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2025\\\/01\\\/10\\\/la-petite-fille-sous-la-neige\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La petite fille sous la neige\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/\",\"name\":\"Le Blog du N\u00e9oprog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#\\\/schema\\\/person\\\/47c594bf12736b172b772f0f02bcf511\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#\\\/schema\\\/person\\\/47c594bf12736b172b772f0f02bcf511\",\"name\":\"Neoprog\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/autoportrait-2.jpg\",\"url\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/autoportrait-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/autoportrait-2.jpg\",\"width\":1024,\"height\":681,\"caption\":\"Neoprog\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/autoportrait-2.jpg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La petite fille sous la neige - Le Blog du N\u00e9oprog","description":"Kiera Templeton, une petite fille de trois ans, dispara\u00eet lors de la grande parade de Thanksgiving \u00e0 New-York en 1998.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.blog.neoprog.eu\/index.php\/2025\/01\/10\/la-petite-fille-sous-la-neige\/","og_locale":"fr_FR","og_type":"article","og_title":"La petite fille sous la neige - Le Blog du N\u00e9oprog","og_description":"Kiera Templeton, une petite fille de trois ans, dispara\u00eet lors de la grande parade de Thanksgiving \u00e0 New-York en 1998.","og_url":"https:\/\/www.blog.neoprog.eu\/index.php\/2025\/01\/10\/la-petite-fille-sous-la-neige\/","og_site_name":"Le Blog du N\u00e9oprog","article_published_time":"2025-01-10T07:00:00+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2025\/01\/la-petite-fille-sous-la-neige.jpeg","type":"image\/jpeg"}],"author":"Neoprog","twitter_card":"summary_large_image","twitter_creator":"@Le_Brun_JC","twitter_site":"@Le_Brun_JC","twitter_misc":{"\u00c9crit par":"Neoprog","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2025\/01\/10\/la-petite-fille-sous-la-neige\/#article","isPartOf":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2025\/01\/10\/la-petite-fille-sous-la-neige\/"},"author":{"name":"Neoprog","@id":"https:\/\/www.blog.neoprog.eu\/#\/schema\/person\/47c594bf12736b172b772f0f02bcf511"},"headline":"La petite fille sous la neige","datePublished":"2025-01-10T07:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2025\/01\/10\/la-petite-fille-sous-la-neige\/"},"wordCount":423,"commentCount":0,"publisher":{"@id":"https:\/\/www.blog.neoprog.eu\/#\/schema\/person\/47c594bf12736b172b772f0f02bcf511"},"image":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2025\/01\/10\/la-petite-fille-sous-la-neige\/#primaryimage"},"thumbnailUrl":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2025\/01\/la-petite-fille-sous-la-neige.jpeg","keywords":["Javier Castillo","Jo\u00ebl Dicker","La petite fille sous la neige","livre","S\u00e9rie TV"],"articleSection":["Livres"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.blog.neoprog.eu\/index.php\/2025\/01\/10\/la-petite-fille-sous-la-neige\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2025\/01\/10\/la-petite-fille-sous-la-neige\/","url":"https:\/\/www.blog.neoprog.eu\/index.php\/2025\/01\/10\/la-petite-fille-sous-la-neige\/","name":"La petite fille sous la neige - Le Blog du N\u00e9oprog","isPartOf":{"@id":"https:\/\/www.blog.neoprog.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2025\/01\/10\/la-petite-fille-sous-la-neige\/#primaryimage"},"image":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2025\/01\/10\/la-petite-fille-sous-la-neige\/#primaryimage"},"thumbnailUrl":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2025\/01\/la-petite-fille-sous-la-neige.jpeg","datePublished":"2025-01-10T07:00:00+00:00","description":"Kiera Templeton, une petite fille de trois ans, dispara\u00eet lors de la grande parade de Thanksgiving \u00e0 New-York en 1998.","breadcrumb":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2025\/01\/10\/la-petite-fille-sous-la-neige\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blog.neoprog.eu\/index.php\/2025\/01\/10\/la-petite-fille-sous-la-neige\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2025\/01\/10\/la-petite-fille-sous-la-neige\/#primaryimage","url":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2025\/01\/la-petite-fille-sous-la-neige.jpeg","contentUrl":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2025\/01\/la-petite-fille-sous-la-neige.jpeg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2025\/01\/10\/la-petite-fille-sous-la-neige\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.blog.neoprog.eu\/"},{"@type":"ListItem","position":2,"name":"La petite fille sous la neige"}]},{"@type":"WebSite","@id":"https:\/\/www.blog.neoprog.eu\/#website","url":"https:\/\/www.blog.neoprog.eu\/","name":"Le Blog du N\u00e9oprog","description":"","publisher":{"@id":"https:\/\/www.blog.neoprog.eu\/#\/schema\/person\/47c594bf12736b172b772f0f02bcf511"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blog.neoprog.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.blog.neoprog.eu\/#\/schema\/person\/47c594bf12736b172b772f0f02bcf511","name":"Neoprog","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2022\/09\/autoportrait-2.jpg","url":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2022\/09\/autoportrait-2.jpg","contentUrl":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2022\/09\/autoportrait-2.jpg","width":1024,"height":681,"caption":"Neoprog"},"logo":{"@id":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2022\/09\/autoportrait-2.jpg"}}]}},"_links":{"self":[{"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/posts\/11171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/comments?post=11171"}],"version-history":[{"count":1,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/posts\/11171\/revisions"}],"predecessor-version":[{"id":11174,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/posts\/11171\/revisions\/11174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/media\/11172"}],"wp:attachment":[{"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/media?parent=11171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/categories?post=11171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/tags?post=11171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}