{"id":12418,"date":"2026-04-11T08:00:00","date_gmt":"2026-04-11T06:00:00","guid":{"rendered":"https:\/\/www.blog.neoprog.eu\/?p=12418"},"modified":"2026-04-10T14:26:28","modified_gmt":"2026-04-10T12:26:28","slug":"marillion-a-strasbourg","status":"publish","type":"post","link":"https:\/\/www.blog.neoprog.eu\/index.php\/2026\/04\/11\/marillion-a-strasbourg\/","title":{"rendered":"Marillion \u00e0 Strasbourg"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2026\/04\/Marillion-1.jpg\" alt=\"\" class=\"wp-image-12420\" srcset=\"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2026\/04\/Marillion-1.jpg 1024w, https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2026\/04\/Marillion-1-300x169.jpg 300w, https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2026\/04\/Marillion-1-768x432.jpg 768w, https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2026\/04\/Marillion-1-500x281.jpg 500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Photo Laurent Regnard pour le magazine Neoprog<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Oui, vous ne r\u00eavez pas, Marillion revient \u00e0 la Laiterie \u00e0 Strasbourg. C\u2019est \u00e9norme ! Quand ? Je ne sais plus trop, en novembre je crois, parce qu\u2019en r\u00e9alit\u00e9, je n\u2019ai pas vraiment envie d\u2019y aller.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Moi qui ai \u00e9t\u00e9 un fan de la premi\u00e8re heure du groupe, qui poss\u00e8de tous leurs albums d\u00e9clin\u00e9s pour certains en plusieurs \u00e9ditions, qui collectionne leurs tee shirts, mugs, sacoches, oui, ce moi n\u2019a plus envie d\u2019aller les \u00e9couter.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je ne suis pas de ceux qui v\u00e9n\u00e8rent la p\u00e9riode Fish et d\u00e9testent Steve Hogarth. En fait j\u2019ai arr\u00eat\u00e9 d\u2019\u00eatre un fan apr\u00e8s l\u2019album Sounds That Can\u2019t Be Made. J\u2019ai continu\u00e9 \u00e0 acheter leurs disques, mais je n\u2019ai plus retrouv\u00e9 le souffle \u00e9pique de \u2018The Invisible Man\u2019, \u2018This Is The 21\u2019st Century\u2019, de \u2018Jigsaw\u2019 ou de \u2018Kayleigh\u2019. Je me suis lass\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En live, j\u2019avoue que les minauderies de Steve Hogarth m\u2019ont toujours agac\u00e9 et le somnolant Steve Rothery m\u2019endort m\u00eame s\u2019il joue divinement bien. En plus, \u00e0 chaque fois, les salles \u00e9taient bond\u00e9es \u00e0 se marcher sur les pieds et \u00e7a n\u2019est pas trop pour me plaire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u2019ai quand m\u00eame h\u00e9sit\u00e9 \u00e0 prendre mon billet. D\u00e9j\u00e0 parce c\u2019est rare que je puisse assister \u00e0 un concert sans prendre la voiture, ensuite et surtout parce que Lazuli assurera la premi\u00e8re partie du show et que j\u2019aime bien <a href=\"https:\/\/www.blog.neoprog.eu\/index.php\/2026\/04\/09\/les-quinze-ans-darpegia\/\" type=\"post\" id=\"12411\">Lazuli<\/a>.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quoiqu\u2019il en soit le concert est sold out maintenant, donc pas de regret. Au pire je d\u00e9gotterai une accr\u00e9ditation photo si je me d\u00e9cide \u00e0 venir, car je n\u2019ai jamais shoot\u00e9 Marillion en live.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bon pour \u00eatre tout \u00e0 fait honn\u00eate avec vous, je manquais d\u2019id\u00e9es pour le billet du samedi, je n\u2019ai pas termin\u00e9 de s\u00e9rie ni de bouquin, je ne vais pas vous parler de les sorties astro toutes les cinq minutes, la crise p\u00e9troli\u00e8re m\u2019importe peu et pour la lune on va d\u2019abord s\u2019assurer que les quatre astronautes reviennent en un seul morceau avant d\u2019en parler.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Donc Marillion\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oui, vous ne r\u00eavez pas, Marillion revient \u00e0 la Laiterie \u00e0 Strasbourg. C\u2019est \u00e9norme ! Quand ? Je ne sais plus trop, en novembre je crois, parce qu\u2019en r\u00e9alit\u00e9, je n\u2019ai pas vraiment envie d\u2019y aller. <a href=\"https:\/\/www.blog.neoprog.eu\/index.php\/2026\/04\/11\/marillion-a-strasbourg\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":12420,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[2873,59,1881,13],"tags":[120,2144,108,402],"class_list":["post-12418","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-concert","category-humeur","category-musiques","category-rock-progressif","tag-concert","tag-lazuli","tag-marillion","tag-strasbourg","post_format-post-format-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marillion \u00e0 Strasbourg - Le Blog du N\u00e9oprog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.blog.neoprog.eu\/index.php\/2026\/04\/11\/marillion-a-strasbourg\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marillion \u00e0 Strasbourg - Le Blog du N\u00e9oprog\" \/>\n<meta property=\"og:description\" content=\"Oui, vous ne r\u00eavez pas, Marillion revient \u00e0 la Laiterie \u00e0 Strasbourg. C\u2019est \u00e9norme ! Quand ? Je ne sais plus trop, en novembre je crois, parce qu\u2019en r\u00e9alit\u00e9, je n\u2019ai pas vraiment envie d\u2019y aller. Continuer la lecture &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blog.neoprog.eu\/index.php\/2026\/04\/11\/marillion-a-strasbourg\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Blog du N\u00e9oprog\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-11T06:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2026\/04\/Marillion-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Neoprog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Le_Brun_JC\" \/>\n<meta name=\"twitter:site\" content=\"@Le_Brun_JC\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Neoprog\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2026\\\/04\\\/11\\\/marillion-a-strasbourg\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2026\\\/04\\\/11\\\/marillion-a-strasbourg\\\/\"},\"author\":{\"name\":\"Neoprog\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#\\\/schema\\\/person\\\/47c594bf12736b172b772f0f02bcf511\"},\"headline\":\"Marillion \u00e0 Strasbourg\",\"datePublished\":\"2026-04-11T06:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2026\\\/04\\\/11\\\/marillion-a-strasbourg\\\/\"},\"wordCount\":375,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#\\\/schema\\\/person\\\/47c594bf12736b172b772f0f02bcf511\"},\"image\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2026\\\/04\\\/11\\\/marillion-a-strasbourg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Marillion-1.jpg\",\"keywords\":[\"concert\",\"Lazuli\",\"marillion\",\"Strasbourg\"],\"articleSection\":[\"concert\",\"Humeurs\",\"Musiques\",\"Rock progressif\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2026\\\/04\\\/11\\\/marillion-a-strasbourg\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2026\\\/04\\\/11\\\/marillion-a-strasbourg\\\/\",\"url\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2026\\\/04\\\/11\\\/marillion-a-strasbourg\\\/\",\"name\":\"Marillion \u00e0 Strasbourg - Le Blog du N\u00e9oprog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2026\\\/04\\\/11\\\/marillion-a-strasbourg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2026\\\/04\\\/11\\\/marillion-a-strasbourg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Marillion-1.jpg\",\"datePublished\":\"2026-04-11T06:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2026\\\/04\\\/11\\\/marillion-a-strasbourg\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2026\\\/04\\\/11\\\/marillion-a-strasbourg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2026\\\/04\\\/11\\\/marillion-a-strasbourg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Marillion-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Marillion-1.jpg\",\"width\":1024,\"height\":576},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2026\\\/04\\\/11\\\/marillion-a-strasbourg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marillion \u00e0 Strasbourg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/\",\"name\":\"Le Blog du N\u00e9oprog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#\\\/schema\\\/person\\\/47c594bf12736b172b772f0f02bcf511\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#\\\/schema\\\/person\\\/47c594bf12736b172b772f0f02bcf511\",\"name\":\"Neoprog\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/autoportrait-2.jpg\",\"url\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/autoportrait-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/autoportrait-2.jpg\",\"width\":1024,\"height\":681,\"caption\":\"Neoprog\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/autoportrait-2.jpg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marillion \u00e0 Strasbourg - Le Blog du N\u00e9oprog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.blog.neoprog.eu\/index.php\/2026\/04\/11\/marillion-a-strasbourg\/","og_locale":"fr_FR","og_type":"article","og_title":"Marillion \u00e0 Strasbourg - Le Blog du N\u00e9oprog","og_description":"Oui, vous ne r\u00eavez pas, Marillion revient \u00e0 la Laiterie \u00e0 Strasbourg. C\u2019est \u00e9norme ! Quand ? Je ne sais plus trop, en novembre je crois, parce qu\u2019en r\u00e9alit\u00e9, je n\u2019ai pas vraiment envie d\u2019y aller. Continuer la lecture &rarr;","og_url":"https:\/\/www.blog.neoprog.eu\/index.php\/2026\/04\/11\/marillion-a-strasbourg\/","og_site_name":"Le Blog du N\u00e9oprog","article_published_time":"2026-04-11T06:00:00+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2026\/04\/Marillion-1.jpg","type":"image\/jpeg"}],"author":"Neoprog","twitter_card":"summary_large_image","twitter_creator":"@Le_Brun_JC","twitter_site":"@Le_Brun_JC","twitter_misc":{"\u00c9crit par":"Neoprog","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2026\/04\/11\/marillion-a-strasbourg\/#article","isPartOf":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2026\/04\/11\/marillion-a-strasbourg\/"},"author":{"name":"Neoprog","@id":"https:\/\/www.blog.neoprog.eu\/#\/schema\/person\/47c594bf12736b172b772f0f02bcf511"},"headline":"Marillion \u00e0 Strasbourg","datePublished":"2026-04-11T06:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2026\/04\/11\/marillion-a-strasbourg\/"},"wordCount":375,"commentCount":2,"publisher":{"@id":"https:\/\/www.blog.neoprog.eu\/#\/schema\/person\/47c594bf12736b172b772f0f02bcf511"},"image":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2026\/04\/11\/marillion-a-strasbourg\/#primaryimage"},"thumbnailUrl":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2026\/04\/Marillion-1.jpg","keywords":["concert","Lazuli","marillion","Strasbourg"],"articleSection":["concert","Humeurs","Musiques","Rock progressif"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.blog.neoprog.eu\/index.php\/2026\/04\/11\/marillion-a-strasbourg\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2026\/04\/11\/marillion-a-strasbourg\/","url":"https:\/\/www.blog.neoprog.eu\/index.php\/2026\/04\/11\/marillion-a-strasbourg\/","name":"Marillion \u00e0 Strasbourg - Le Blog du N\u00e9oprog","isPartOf":{"@id":"https:\/\/www.blog.neoprog.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2026\/04\/11\/marillion-a-strasbourg\/#primaryimage"},"image":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2026\/04\/11\/marillion-a-strasbourg\/#primaryimage"},"thumbnailUrl":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2026\/04\/Marillion-1.jpg","datePublished":"2026-04-11T06:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2026\/04\/11\/marillion-a-strasbourg\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blog.neoprog.eu\/index.php\/2026\/04\/11\/marillion-a-strasbourg\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2026\/04\/11\/marillion-a-strasbourg\/#primaryimage","url":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2026\/04\/Marillion-1.jpg","contentUrl":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2026\/04\/Marillion-1.jpg","width":1024,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2026\/04\/11\/marillion-a-strasbourg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.blog.neoprog.eu\/"},{"@type":"ListItem","position":2,"name":"Marillion \u00e0 Strasbourg"}]},{"@type":"WebSite","@id":"https:\/\/www.blog.neoprog.eu\/#website","url":"https:\/\/www.blog.neoprog.eu\/","name":"Le Blog du N\u00e9oprog","description":"","publisher":{"@id":"https:\/\/www.blog.neoprog.eu\/#\/schema\/person\/47c594bf12736b172b772f0f02bcf511"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blog.neoprog.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.blog.neoprog.eu\/#\/schema\/person\/47c594bf12736b172b772f0f02bcf511","name":"Neoprog","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2022\/09\/autoportrait-2.jpg","url":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2022\/09\/autoportrait-2.jpg","contentUrl":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2022\/09\/autoportrait-2.jpg","width":1024,"height":681,"caption":"Neoprog"},"logo":{"@id":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2022\/09\/autoportrait-2.jpg"}}]}},"_links":{"self":[{"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/posts\/12418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/comments?post=12418"}],"version-history":[{"count":2,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/posts\/12418\/revisions"}],"predecessor-version":[{"id":12423,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/posts\/12418\/revisions\/12423"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/media\/12420"}],"wp:attachment":[{"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/media?parent=12418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/categories?post=12418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/tags?post=12418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}