{"id":3530,"date":"2018-04-16T07:26:47","date_gmt":"2018-04-16T05:26:47","guid":{"rendered":"http:\/\/www.blog.neoprog.eu\/?p=3530"},"modified":"2018-04-16T07:26:47","modified_gmt":"2018-04-16T05:26:47","slug":"dix-minutes","status":"publish","type":"post","link":"https:\/\/www.blog.neoprog.eu\/index.php\/2018\/04\/16\/dix-minutes\/","title":{"rendered":"Dix minutes"},"content":{"rendered":"<p><a href=\"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2018\/04\/marseille.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3541\" src=\"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2018\/04\/marseille.jpg\" alt=\"\" width=\"880\" height=\"241\" srcset=\"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2018\/04\/marseille.jpg 880w, https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2018\/04\/marseille-300x82.jpg 300w, https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2018\/04\/marseille-768x210.jpg 768w, https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2018\/04\/marseille-500x137.jpg 500w\" sizes=\"auto, (max-width: 880px) 100vw, 880px\" \/><\/a>Mon petit devait passer un entretien pour rentrer dans une \u00e9cole d&rsquo;architecture \u00e0 Marseille. A la base, je n&rsquo;imaginais m\u00eame pas qu&rsquo;il serait convoqu\u00e9, malgr\u00e9 de bonnes notes. Il sortait d&rsquo;un bac pro&#8230;<\/p>\n<p>Nous nous disions qu&rsquo;au pire l&rsquo;entretien se d\u00e9roulerait via Skype comme le propose d&rsquo;autres \u00e9coles.<\/p>\n<p>Mais vendredi, c&rsquo;\u00e9tait le 13 avril, 13 comme num\u00e9ro le d\u00e9partement de Marseille, 13 comme un vendredi 13. Pas d&rsquo;entretien Skype, gr\u00e8ves de la SNCF vendredi et samedi, il fallait que notre petit sorte du nid pour se rendre chez les sudistes. Pas de train, pas d&rsquo;avion aller-retour, une Logan pour tout v\u00e9hicule, il faillait improviser. Jeudi soir, ma femme, mon fils et moi \u00e9tions sur nos ordinateurs et smartphones \u00e0 la recherche de la bonne combinaison \u00e0 pied \u00e0 cheval, en voiture : avion, trottinette, nage, train, cheval, voiture, stop, marche \u00e0 pied, t\u00e9l\u00e9portation, v\u00e9lo, fus\u00e9e, bateau&#8230;<\/p>\n<p>Apr\u00e8s moultes recherches, contacts, la solution viendra de Blablacar et Airbnb.<\/p>\n<ul>\n<li>Vendredi 13 &#8211; Illkirch &#8211; Strasbourg 15 min<\/li>\n<li>Vendredi 13 &#8211; Strasbourg &#8211; Manosque 8h00<\/li>\n<li>Samedi 14 &#8211; Manosque &#8211; Marseille 1h30<\/li>\n<li>Samedi 14 &#8211; Marseille Prado &#8211; Ecole nationale sup\u00e9rieure d&rsquo;architecture de Marseille 50 min<\/li>\n<li>Samedi 14 &#8211; Ecole nationale sup\u00e9rieure d&rsquo;architecture de Marseille &#8211; Boulevard de Font S\u00e9gune 40 min<\/li>\n<li>Dimanche 15 &#8211; Boulevard de Font S\u00e9gune &#8211; Gare Saint Charles 35 min<\/li>\n<li>Dimanche 15 &#8211; Marseille &#8211; Strasbourg 8h00<\/li>\n<li>Dimanche 15 &#8211; Strasbourg &#8211; Illkirch 15 min<\/li>\n<\/ul>\n<p>Trois jours dont vingt heures de transport pour dix minutes d&rsquo;entretien.<\/p>\n<p>C&rsquo;\u00e9tait le plan. Mais voila. Le Blabacar Marseille &#8211; Strasbourg fait le mort, du coup nous r\u00e9servons un billet de train retour pour le dimanche en esp\u00e9rant que le train circulera. Ensuite l&rsquo;h\u00f4te de la chambre Airbnb valid\u00e9e, nous informe qu&rsquo;elle est en vacances pour deux semaines, que son compte a \u00e9t\u00e9 pirat\u00e9. Du coup r\u00e9clamation aupr\u00e8s Airbnb et recherche d&rsquo;une nouvelle chambre dans le coin. Une vraie gal\u00e8re : les chambres annonc\u00e9es disponibles ne le sont pas ou les propri\u00e9taires sont absents, bref l&rsquo;horreur. Quatre r\u00e9servations Airbnb, deux annulations, un remboursement, une r\u00e9clamation, trois r\u00e9servations Blablacar, un changement de point de d\u00e9part, une annulation. Les voyages 2.0 ne forment pas la jeunesse, ils cassent les c&#8230;&#8230; des parents. Vivent les h\u00f4teliers, Air-France et la SCNF !<\/p>\n<p>Notre tout petit (1m85) \u00e0 peine sorti du nid (18 ans) et qui ne s&rsquo;est jamais aventur\u00e9 tr\u00e8s loin de la maison, partait tout seul \u00e0 l&rsquo;aventure, \u00e0 Marseille, la ville du sud, de la violence, du crime, des r\u00e8glements de comptes, de la mafia, des hommes politiques v\u00e9reux.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mon petit devait passer un entretien pour rentrer dans une \u00e9cole d&rsquo;architecture \u00e0 Marseille. A la base, je n&rsquo;imaginais m\u00eame pas qu&rsquo;il serait convoqu\u00e9, malgr\u00e9 de bonnes notes. Il sortait d&rsquo;un bac pro&#8230; Nous nous disions qu&rsquo;au pire l&rsquo;entretien se &hellip; <a href=\"https:\/\/www.blog.neoprog.eu\/index.php\/2018\/04\/16\/dix-minutes\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[59],"tags":[917,921,918,922,923,919,920],"class_list":["post-3530","post","type-post","status-publish","format-image","hentry","category-humeur","tag-airbnb","tag-architecture","tag-blablacar","tag-galere","tag-marseille","tag-paypal","tag-sncf","post_format-post-format-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dix minutes - Le Blog du N\u00e9oprog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.blog.neoprog.eu\/index.php\/2018\/04\/16\/dix-minutes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dix minutes - Le Blog du N\u00e9oprog\" \/>\n<meta property=\"og:description\" content=\"Mon petit devait passer un entretien pour rentrer dans une \u00e9cole d&rsquo;architecture \u00e0 Marseille. A la base, je n&rsquo;imaginais m\u00eame pas qu&rsquo;il serait convoqu\u00e9, malgr\u00e9 de bonnes notes. Il sortait d&rsquo;un bac pro&#8230; Nous nous disions qu&rsquo;au pire l&rsquo;entretien se &hellip; Continuer la lecture &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blog.neoprog.eu\/index.php\/2018\/04\/16\/dix-minutes\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Blog du N\u00e9oprog\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-16T05:26:47+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2018\/04\/marseille.jpg\" \/>\n<meta name=\"author\" content=\"Neoprog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Le_Brun_JC\" \/>\n<meta name=\"twitter:site\" content=\"@Le_Brun_JC\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Neoprog\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2018\\\/04\\\/16\\\/dix-minutes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2018\\\/04\\\/16\\\/dix-minutes\\\/\"},\"author\":{\"name\":\"Neoprog\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#\\\/schema\\\/person\\\/47c594bf12736b172b772f0f02bcf511\"},\"headline\":\"Dix minutes\",\"datePublished\":\"2018-04-16T05:26:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2018\\\/04\\\/16\\\/dix-minutes\\\/\"},\"wordCount\":430,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#\\\/schema\\\/person\\\/47c594bf12736b172b772f0f02bcf511\"},\"image\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2018\\\/04\\\/16\\\/dix-minutes\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/marseille.jpg\",\"keywords\":[\"Airbnb\",\"architecture\",\"Blablacar\",\"gal\u00e8re\",\"Marseille\",\"Paypal\",\"SNCF\"],\"articleSection\":[\"Humeurs\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2018\\\/04\\\/16\\\/dix-minutes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2018\\\/04\\\/16\\\/dix-minutes\\\/\",\"url\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2018\\\/04\\\/16\\\/dix-minutes\\\/\",\"name\":\"Dix minutes - Le Blog du N\u00e9oprog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2018\\\/04\\\/16\\\/dix-minutes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2018\\\/04\\\/16\\\/dix-minutes\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/marseille.jpg\",\"datePublished\":\"2018-04-16T05:26:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2018\\\/04\\\/16\\\/dix-minutes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2018\\\/04\\\/16\\\/dix-minutes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2018\\\/04\\\/16\\\/dix-minutes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/marseille.jpg\",\"contentUrl\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/marseille.jpg\",\"width\":880,\"height\":241},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2018\\\/04\\\/16\\\/dix-minutes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dix minutes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/\",\"name\":\"Le Blog du N\u00e9oprog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#\\\/schema\\\/person\\\/47c594bf12736b172b772f0f02bcf511\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#\\\/schema\\\/person\\\/47c594bf12736b172b772f0f02bcf511\",\"name\":\"Neoprog\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/autoportrait-2.jpg\",\"url\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/autoportrait-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/autoportrait-2.jpg\",\"width\":1024,\"height\":681,\"caption\":\"Neoprog\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/autoportrait-2.jpg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dix minutes - Le Blog du N\u00e9oprog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.blog.neoprog.eu\/index.php\/2018\/04\/16\/dix-minutes\/","og_locale":"fr_FR","og_type":"article","og_title":"Dix minutes - Le Blog du N\u00e9oprog","og_description":"Mon petit devait passer un entretien pour rentrer dans une \u00e9cole d&rsquo;architecture \u00e0 Marseille. A la base, je n&rsquo;imaginais m\u00eame pas qu&rsquo;il serait convoqu\u00e9, malgr\u00e9 de bonnes notes. Il sortait d&rsquo;un bac pro&#8230; Nous nous disions qu&rsquo;au pire l&rsquo;entretien se &hellip; Continuer la lecture &rarr;","og_url":"https:\/\/www.blog.neoprog.eu\/index.php\/2018\/04\/16\/dix-minutes\/","og_site_name":"Le Blog du N\u00e9oprog","article_published_time":"2018-04-16T05:26:47+00:00","og_image":[{"url":"http:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2018\/04\/marseille.jpg","type":"","width":"","height":""}],"author":"Neoprog","twitter_card":"summary_large_image","twitter_creator":"@Le_Brun_JC","twitter_site":"@Le_Brun_JC","twitter_misc":{"\u00c9crit par":"Neoprog","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2018\/04\/16\/dix-minutes\/#article","isPartOf":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2018\/04\/16\/dix-minutes\/"},"author":{"name":"Neoprog","@id":"https:\/\/www.blog.neoprog.eu\/#\/schema\/person\/47c594bf12736b172b772f0f02bcf511"},"headline":"Dix minutes","datePublished":"2018-04-16T05:26:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2018\/04\/16\/dix-minutes\/"},"wordCount":430,"commentCount":0,"publisher":{"@id":"https:\/\/www.blog.neoprog.eu\/#\/schema\/person\/47c594bf12736b172b772f0f02bcf511"},"image":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2018\/04\/16\/dix-minutes\/#primaryimage"},"thumbnailUrl":"http:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2018\/04\/marseille.jpg","keywords":["Airbnb","architecture","Blablacar","gal\u00e8re","Marseille","Paypal","SNCF"],"articleSection":["Humeurs"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.blog.neoprog.eu\/index.php\/2018\/04\/16\/dix-minutes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2018\/04\/16\/dix-minutes\/","url":"https:\/\/www.blog.neoprog.eu\/index.php\/2018\/04\/16\/dix-minutes\/","name":"Dix minutes - Le Blog du N\u00e9oprog","isPartOf":{"@id":"https:\/\/www.blog.neoprog.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2018\/04\/16\/dix-minutes\/#primaryimage"},"image":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2018\/04\/16\/dix-minutes\/#primaryimage"},"thumbnailUrl":"http:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2018\/04\/marseille.jpg","datePublished":"2018-04-16T05:26:47+00:00","breadcrumb":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2018\/04\/16\/dix-minutes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blog.neoprog.eu\/index.php\/2018\/04\/16\/dix-minutes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2018\/04\/16\/dix-minutes\/#primaryimage","url":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2018\/04\/marseille.jpg","contentUrl":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2018\/04\/marseille.jpg","width":880,"height":241},{"@type":"BreadcrumbList","@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2018\/04\/16\/dix-minutes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.blog.neoprog.eu\/"},{"@type":"ListItem","position":2,"name":"Dix minutes"}]},{"@type":"WebSite","@id":"https:\/\/www.blog.neoprog.eu\/#website","url":"https:\/\/www.blog.neoprog.eu\/","name":"Le Blog du N\u00e9oprog","description":"","publisher":{"@id":"https:\/\/www.blog.neoprog.eu\/#\/schema\/person\/47c594bf12736b172b772f0f02bcf511"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blog.neoprog.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.blog.neoprog.eu\/#\/schema\/person\/47c594bf12736b172b772f0f02bcf511","name":"Neoprog","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2022\/09\/autoportrait-2.jpg","url":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2022\/09\/autoportrait-2.jpg","contentUrl":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2022\/09\/autoportrait-2.jpg","width":1024,"height":681,"caption":"Neoprog"},"logo":{"@id":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2022\/09\/autoportrait-2.jpg"}}]}},"_links":{"self":[{"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/posts\/3530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/comments?post=3530"}],"version-history":[{"count":11,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/posts\/3530\/revisions"}],"predecessor-version":[{"id":3556,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/posts\/3530\/revisions\/3556"}],"wp:attachment":[{"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/media?parent=3530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/categories?post=3530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/tags?post=3530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}