{"id":5484,"date":"2019-10-29T08:35:33","date_gmt":"2019-10-29T07:35:33","guid":{"rendered":"http:\/\/www.blog.neoprog.eu\/?p=5484"},"modified":"2019-10-29T08:35:33","modified_gmt":"2019-10-29T07:35:33","slug":"edimbourg","status":"publish","type":"post","link":"https:\/\/www.blog.neoprog.eu\/index.php\/2019\/10\/29\/edimbourg\/","title":{"rendered":"Edimbourg"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2019\/10\/misplaced-1024x512.jpg\" alt=\"\" class=\"wp-image-5485\" srcset=\"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2019\/10\/misplaced.jpg 1024w, https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2019\/10\/misplaced-300x150.jpg 300w, https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2019\/10\/misplaced-768x384.jpg 768w, https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2019\/10\/misplaced-500x250.jpg 500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>En 1990, je partis avec un ami de longue date pour un p\u00e9riple \u00e9cossais. Notre objectif se situait \u00e0 l&rsquo;extr\u00eame nord des terres des MacLeod, un petit archipel d&rsquo;\u00eeles nomm\u00e9es les Orcades. Apr\u00e8s un passage mouvement\u00e9 \u00e0 Londres en pleine Pool Tax, nous rejoign\u00eemes la ville d&rsquo;Edimbourg en bus, franchissant le mur d&rsquo;Adrien, quittant les anglais pour les kilts mangeurs de panse de brebis farcie.<\/p>\n\n\n\n<p>Edimbourg, outre la beaut\u00e9 de la ville, se devait d&rsquo;\u00eatre un p\u00e8lerinage obligatoire pour mon camarade et moi m\u00eame. S&rsquo;il m&rsquo;avait initi\u00e9 \u00e0 Genesis, Peter Gabriel et Steve Hackett, je lui avait fait d\u00e9couvrir Marillion et le personnage de Fish l&rsquo;avait fascin\u00e9. Misplaced Childhood \u00e9tait sorti en 1985 et Clutching At Straws en 1987. Les paroles du po\u00e8te maudit William Dereck Dick hantaient nos esprits et marcher sur le Royal Mile, trainer dans les pubs et admirer the Heart Of Liothian \u00e9tait un devoir de fan.<\/p>\n\n\n\n<p>Misplaced est consid\u00e9r\u00e9 \u00e0 raison comme le chef d&rsquo;oeuvre du groupe Marillion p\u00e9riode Fish. Les chiffres parlent d&rsquo;eux m\u00eame : 1er des charts anglais pendant 42 semaines, 3\u00e8me en Allemagne pendant 45 semaines, un succ\u00e8s commercial et artistiques. Les <a href=\"https:\/\/www.neoprog.eu\/chronique\/marillion\/misplaced_childhood\">chroniques<\/a> de cet album qui fait toujours r\u00e9f\u00e9rence aujourd&rsquo;hui sont l\u00e9gion sur la toile et les avis sont quasiment unanimes. Il faut dire que Fish s&rsquo;y met \u00e0 nu comme jamais, avant d&rsquo;entamer la longue descente aux enfers qui le conduira \u00e0 Clutching puis \u00e0 se faire virer du groupe qui accouchera dans la douleur d&rsquo;un Season&rsquo;s End en 1989 avec Steve Hogarth au chant.<\/p>\n\n\n\n<p>Misplaced Childhood repr\u00e9sente le sommet de la carri\u00e8re du groupe Marillion, seulement apr\u00e8s trois albums, la cons\u00e9cration m\u00e9diatique et celle du public, des concerts partout dans le monde, et une maison de disque qui se met \u00e0 r\u00eaver de tubes \u00e0 r\u00e9p\u00e9tition. Mais c&rsquo;est surtout un album sur l&rsquo;enfance, l&rsquo;enfance perdue de Fish racont\u00e9e avec les fabuleuses guitares de Rothery et les claviers de Kelly.<\/p>\n\n\n\n<p>Apr\u00e8s Edimbourg, son ch\u00e2teau, ses pubs, ses rues, sa colline et ses souvenirs, nous remont\u00e2mes vers le nord, Inverness, Thurso puis la travers\u00e9e jusque Stromness o\u00f9 d\u00e9butait notre p\u00e9riple dans les Orcades. Apr\u00e8s l&rsquo;enfance de Fish, nous explorions l&rsquo;enfance de l&rsquo;humanit\u00e9 au milieu des cairns, tumulus, villages de l&rsquo;\u00e2ge de fer et ses <a href=\"https:\/\/www.neoprog.eu\/chronique\/moon_letters\/until_they_feel_the_sun\">selkies<\/a>.<\/p>\n\n\n\n<p>Si vous allez \u00e0 Edimbourg, emportez avec vous l&rsquo;album Misplaced Childhood, marchez sur les pav\u00e9s du <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Royal_Mile\">Royal Mile<\/a>, d\u00e9couvrez le coeur du Lothian, d\u00e9gustez une bi\u00e8re \u00e0 la m\u00e9moire de l&rsquo;enfant que fut Fish en buvant les paroles de Kayleigh. Vous n&rsquo;\u00e9couterez plus jamais l&rsquo;album de la m\u00eame mani\u00e8re ensuite.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En 1990, je partis avec un ami de longue date pour un p\u00e9riple \u00e9cossais. Notre objectif se situait \u00e0 l&rsquo;extr\u00eame nord des terres des MacLeod, un petit archipel d&rsquo;\u00eeles nomm\u00e9es les Orcades. Apr\u00e8s un passage mouvement\u00e9 \u00e0 Londres en pleine &hellip; <a href=\"https:\/\/www.blog.neoprog.eu\/index.php\/2019\/10\/29\/edimbourg\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":5485,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,13],"tags":[1434,1432,701,564,1433,108,362],"class_list":["post-5484","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musique","category-rock-progressif","tag-ecosse","tag-edimbourg","tag-enfance","tag-fish","tag-lothian","tag-marillion","tag-voyage"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Edimbourg - Le Blog du N\u00e9oprog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.blog.neoprog.eu\/index.php\/2019\/10\/29\/edimbourg\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Edimbourg - Le Blog du N\u00e9oprog\" \/>\n<meta property=\"og:description\" content=\"En 1990, je partis avec un ami de longue date pour un p\u00e9riple \u00e9cossais. Notre objectif se situait \u00e0 l&rsquo;extr\u00eame nord des terres des MacLeod, un petit archipel d&rsquo;\u00eeles nomm\u00e9es les Orcades. Apr\u00e8s un passage mouvement\u00e9 \u00e0 Londres en pleine &hellip; Continuer la lecture &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blog.neoprog.eu\/index.php\/2019\/10\/29\/edimbourg\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Blog du N\u00e9oprog\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-29T07:35:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2019\/10\/misplaced.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Neoprog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Le_Brun_JC\" \/>\n<meta name=\"twitter:site\" content=\"@Le_Brun_JC\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Neoprog\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2019\\\/10\\\/29\\\/edimbourg\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2019\\\/10\\\/29\\\/edimbourg\\\/\"},\"author\":{\"name\":\"Neoprog\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#\\\/schema\\\/person\\\/47c594bf12736b172b772f0f02bcf511\"},\"headline\":\"Edimbourg\",\"datePublished\":\"2019-10-29T07:35:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2019\\\/10\\\/29\\\/edimbourg\\\/\"},\"wordCount\":450,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#\\\/schema\\\/person\\\/47c594bf12736b172b772f0f02bcf511\"},\"image\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2019\\\/10\\\/29\\\/edimbourg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/misplaced.jpg\",\"keywords\":[\"\u00e9cosse\",\"Edimbourg\",\"enfance\",\"Fish\",\"Lothian\",\"marillion\",\"voyage\"],\"articleSection\":[\"musique\",\"Rock progressif\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2019\\\/10\\\/29\\\/edimbourg\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2019\\\/10\\\/29\\\/edimbourg\\\/\",\"url\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2019\\\/10\\\/29\\\/edimbourg\\\/\",\"name\":\"Edimbourg - Le Blog du N\u00e9oprog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2019\\\/10\\\/29\\\/edimbourg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2019\\\/10\\\/29\\\/edimbourg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/misplaced.jpg\",\"datePublished\":\"2019-10-29T07:35:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2019\\\/10\\\/29\\\/edimbourg\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2019\\\/10\\\/29\\\/edimbourg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2019\\\/10\\\/29\\\/edimbourg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/misplaced.jpg\",\"contentUrl\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/misplaced.jpg\",\"width\":1024,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2019\\\/10\\\/29\\\/edimbourg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Edimbourg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/\",\"name\":\"Le Blog du N\u00e9oprog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#\\\/schema\\\/person\\\/47c594bf12736b172b772f0f02bcf511\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#\\\/schema\\\/person\\\/47c594bf12736b172b772f0f02bcf511\",\"name\":\"Neoprog\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/autoportrait-2.jpg\",\"url\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/autoportrait-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/autoportrait-2.jpg\",\"width\":1024,\"height\":681,\"caption\":\"Neoprog\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/autoportrait-2.jpg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Edimbourg - Le Blog du N\u00e9oprog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.blog.neoprog.eu\/index.php\/2019\/10\/29\/edimbourg\/","og_locale":"fr_FR","og_type":"article","og_title":"Edimbourg - Le Blog du N\u00e9oprog","og_description":"En 1990, je partis avec un ami de longue date pour un p\u00e9riple \u00e9cossais. Notre objectif se situait \u00e0 l&rsquo;extr\u00eame nord des terres des MacLeod, un petit archipel d&rsquo;\u00eeles nomm\u00e9es les Orcades. Apr\u00e8s un passage mouvement\u00e9 \u00e0 Londres en pleine &hellip; Continuer la lecture &rarr;","og_url":"https:\/\/www.blog.neoprog.eu\/index.php\/2019\/10\/29\/edimbourg\/","og_site_name":"Le Blog du N\u00e9oprog","article_published_time":"2019-10-29T07:35:33+00:00","og_image":[{"width":1024,"height":512,"url":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2019\/10\/misplaced.jpg","type":"image\/jpeg"}],"author":"Neoprog","twitter_card":"summary_large_image","twitter_creator":"@Le_Brun_JC","twitter_site":"@Le_Brun_JC","twitter_misc":{"\u00c9crit par":"Neoprog","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2019\/10\/29\/edimbourg\/#article","isPartOf":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2019\/10\/29\/edimbourg\/"},"author":{"name":"Neoprog","@id":"https:\/\/www.blog.neoprog.eu\/#\/schema\/person\/47c594bf12736b172b772f0f02bcf511"},"headline":"Edimbourg","datePublished":"2019-10-29T07:35:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2019\/10\/29\/edimbourg\/"},"wordCount":450,"commentCount":0,"publisher":{"@id":"https:\/\/www.blog.neoprog.eu\/#\/schema\/person\/47c594bf12736b172b772f0f02bcf511"},"image":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2019\/10\/29\/edimbourg\/#primaryimage"},"thumbnailUrl":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2019\/10\/misplaced.jpg","keywords":["\u00e9cosse","Edimbourg","enfance","Fish","Lothian","marillion","voyage"],"articleSection":["musique","Rock progressif"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.blog.neoprog.eu\/index.php\/2019\/10\/29\/edimbourg\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2019\/10\/29\/edimbourg\/","url":"https:\/\/www.blog.neoprog.eu\/index.php\/2019\/10\/29\/edimbourg\/","name":"Edimbourg - Le Blog du N\u00e9oprog","isPartOf":{"@id":"https:\/\/www.blog.neoprog.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2019\/10\/29\/edimbourg\/#primaryimage"},"image":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2019\/10\/29\/edimbourg\/#primaryimage"},"thumbnailUrl":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2019\/10\/misplaced.jpg","datePublished":"2019-10-29T07:35:33+00:00","breadcrumb":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2019\/10\/29\/edimbourg\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blog.neoprog.eu\/index.php\/2019\/10\/29\/edimbourg\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2019\/10\/29\/edimbourg\/#primaryimage","url":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2019\/10\/misplaced.jpg","contentUrl":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2019\/10\/misplaced.jpg","width":1024,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2019\/10\/29\/edimbourg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.blog.neoprog.eu\/"},{"@type":"ListItem","position":2,"name":"Edimbourg"}]},{"@type":"WebSite","@id":"https:\/\/www.blog.neoprog.eu\/#website","url":"https:\/\/www.blog.neoprog.eu\/","name":"Le Blog du N\u00e9oprog","description":"","publisher":{"@id":"https:\/\/www.blog.neoprog.eu\/#\/schema\/person\/47c594bf12736b172b772f0f02bcf511"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blog.neoprog.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.blog.neoprog.eu\/#\/schema\/person\/47c594bf12736b172b772f0f02bcf511","name":"Neoprog","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2022\/09\/autoportrait-2.jpg","url":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2022\/09\/autoportrait-2.jpg","contentUrl":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2022\/09\/autoportrait-2.jpg","width":1024,"height":681,"caption":"Neoprog"},"logo":{"@id":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2022\/09\/autoportrait-2.jpg"}}]}},"_links":{"self":[{"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/posts\/5484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/comments?post=5484"}],"version-history":[{"count":5,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/posts\/5484\/revisions"}],"predecessor-version":[{"id":5490,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/posts\/5484\/revisions\/5490"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/media\/5485"}],"wp:attachment":[{"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/media?parent=5484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/categories?post=5484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/tags?post=5484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}