{"id":6848,"date":"2021-05-05T07:00:00","date_gmt":"2021-05-05T05:00:00","guid":{"rendered":"http:\/\/www.blog.neoprog.eu\/?p=6848"},"modified":"2021-05-03T12:22:14","modified_gmt":"2021-05-03T10:22:14","slug":"apollo-soyouz","status":"publish","type":"post","link":"https:\/\/www.blog.neoprog.eu\/index.php\/2021\/05\/05\/apollo-soyouz\/","title":{"rendered":"Apollo-Soyouz"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2021\/04\/apollo-soyouz.jpg\" alt=\"\" class=\"wp-image-6849\" srcset=\"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2021\/04\/apollo-soyouz.jpg 1024w, https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2021\/04\/apollo-soyouz-300x169.jpg 300w, https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2021\/04\/apollo-soyouz-768x432.jpg 768w, https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2021\/04\/apollo-soyouz-500x281.jpg 500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Je me souviens parfaitement de cette poign\u00e9e de main orbitale en 1975, lorsque qu\u2019un module Soyouz s\u2019arrima \u00e0 une capsule Apollo. Un bonjour m\u00e9diatique terriblement cher pour l\u2019\u00e9poque. Mais c\u2019\u00e9tait la Guerre Froide et toute d\u00e9tente \u00e9tait bonne \u00e0 prendre.<\/p>\n\n\n\n<p>En parlant de d\u00e9tente, savez-vous qu\u2019utiliser une arme \u00e0 feu dans l\u2019espace est une bien mauvaise id\u00e9e ? Non ? Alors regardez la deuxi\u00e8me saison de <a href=\"https:\/\/www.blog.neoprog.eu\/index.php\/2020\/11\/24\/la-lune-rouge\/\">For All Mankind<\/a>.<\/p>\n\n\n\n<p>Comme on change pas une \u00e9quipe qui gagne, les ricains et les ruskoff se chamaillent sur la Terre et sur la Lune. La NASA envisage d\u2019armer sa nouvelle navette spatiale \u00e0 propulsion nucl\u00e9aire et la base lunaire est occup\u00e9e en permanence par toute une \u00e9quipe d\u2019astronautes.<\/p>\n\n\n\n<p>Nous nageons en pleine science-fiction et pourtant la saison nous ram\u00e8ne aux ann\u00e9es Reagan. En fait For All Mankind, avec ces Russes premiers \u00e0 fouler le sol lunaire suit la trajectoire de plus en plus divergente d\u2019une uchronie. Mais nous le savions d\u00e9j\u00e0.<\/p>\n\n\n\n<p>Ne nous mentons, si la saison une semblait pleine d\u2019espoir, la saison deux nous conduit au bord du pr\u00e9cipice. Les astronautes tirent \u00e0 vue, leurs \u00e9pouses les trompent, les enfants font n\u2019importe quoi et quelques personnes v\u00eatues de scaphandres pressuris\u00e9s ou recouvertes de scotch am\u00e9ricain perdent la vie \u00e0 la surface de notre satellite.<\/p>\n\n\n\n<p>Et pendant ce temps, russes et am\u00e9ricains, entre deux sc\u00e9narios de fin du monde, mettent au point le couplage improbable d\u2019Apollo et de Soyouz. Tout cela pour une poign\u00e9e de main qui pourrait sauver l\u2019humanit\u00e9 d\u2019une apocalypse nucl\u00e9aire.<\/p>\n\n\n\n<p>La seconde saison de All Mankind tient ses promesses et si tout va bien, en 1995 l\u2019homme marchera sur Mars. Sera-t-il am\u00e9ricain, russe, chinois ou serait-ce jeune Jean-Loup Chr\u00e9tien (Thomas \u00e9tait trop jeune), vous le saurez en regardant la saison trois.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"For All Mankind \u2014 Season 2 Trailer | Apple TV+\" width=\"584\" height=\"329\" src=\"https:\/\/www.youtube.com\/embed\/zzmrmjlESjQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Je me souviens parfaitement de cette poign\u00e9e de main orbitale en 1975, lorsque qu\u2019un module Soyouz s\u2019arrima \u00e0 une capsule Apollo. <a href=\"https:\/\/www.blog.neoprog.eu\/index.php\/2021\/05\/05\/apollo-soyouz\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":6849,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[1311,410,422],"tags":[1878,50,1879,1713,180,426],"class_list":["post-6848","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-apple","category-science-fiction","category-serie-tv","tag-apollo-soyouz","tag-espace","tag-for-all-mankind","tag-guerre-froide","tag-lune","tag-serie-tv","post_format-post-format-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Apollo-Soyouz - Le Blog du N\u00e9oprog<\/title>\n<meta name=\"description\" content=\"Je me souviens parfaitement de cette poign\u00e9e de main orbitale en 1975, lorsque qu\u2019un module Soyouz s\u2019arrima \u00e0 une capsule Apollo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.blog.neoprog.eu\/index.php\/2021\/05\/05\/apollo-soyouz\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apollo-Soyouz - Le Blog du N\u00e9oprog\" \/>\n<meta property=\"og:description\" content=\"Je me souviens parfaitement de cette poign\u00e9e de main orbitale en 1975, lorsque qu\u2019un module Soyouz s\u2019arrima \u00e0 une capsule Apollo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blog.neoprog.eu\/index.php\/2021\/05\/05\/apollo-soyouz\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Blog du N\u00e9oprog\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-05T05:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2021\/04\/apollo-soyouz.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Neoprog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Le_Brun_JC\" \/>\n<meta name=\"twitter:site\" content=\"@Le_Brun_JC\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Neoprog\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2021\\\/05\\\/05\\\/apollo-soyouz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2021\\\/05\\\/05\\\/apollo-soyouz\\\/\"},\"author\":{\"name\":\"Neoprog\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#\\\/schema\\\/person\\\/47c594bf12736b172b772f0f02bcf511\"},\"headline\":\"Apollo-Soyouz\",\"datePublished\":\"2021-05-05T05:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2021\\\/05\\\/05\\\/apollo-soyouz\\\/\"},\"wordCount\":321,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#\\\/schema\\\/person\\\/47c594bf12736b172b772f0f02bcf511\"},\"image\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2021\\\/05\\\/05\\\/apollo-soyouz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/apollo-soyouz.jpg\",\"keywords\":[\"Apollo-Soyouz\",\"espace\",\"For All Mankind\",\"guerre froide\",\"lune\",\"S\u00e9rie TV\"],\"articleSection\":[\"Apple\",\"science-fiction\",\"S\u00e9ries TV\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2021\\\/05\\\/05\\\/apollo-soyouz\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2021\\\/05\\\/05\\\/apollo-soyouz\\\/\",\"url\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2021\\\/05\\\/05\\\/apollo-soyouz\\\/\",\"name\":\"Apollo-Soyouz - Le Blog du N\u00e9oprog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2021\\\/05\\\/05\\\/apollo-soyouz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2021\\\/05\\\/05\\\/apollo-soyouz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/apollo-soyouz.jpg\",\"datePublished\":\"2021-05-05T05:00:00+00:00\",\"description\":\"Je me souviens parfaitement de cette poign\u00e9e de main orbitale en 1975, lorsque qu\u2019un module Soyouz s\u2019arrima \u00e0 une capsule Apollo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2021\\\/05\\\/05\\\/apollo-soyouz\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2021\\\/05\\\/05\\\/apollo-soyouz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2021\\\/05\\\/05\\\/apollo-soyouz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/apollo-soyouz.jpg\",\"contentUrl\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/apollo-soyouz.jpg\",\"width\":1024,\"height\":576},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/index.php\\\/2021\\\/05\\\/05\\\/apollo-soyouz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apollo-Soyouz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/\",\"name\":\"Le Blog du N\u00e9oprog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#\\\/schema\\\/person\\\/47c594bf12736b172b772f0f02bcf511\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/#\\\/schema\\\/person\\\/47c594bf12736b172b772f0f02bcf511\",\"name\":\"Neoprog\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/autoportrait-2.jpg\",\"url\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/autoportrait-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/autoportrait-2.jpg\",\"width\":1024,\"height\":681,\"caption\":\"Neoprog\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.blog.neoprog.eu\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/autoportrait-2.jpg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apollo-Soyouz - Le Blog du N\u00e9oprog","description":"Je me souviens parfaitement de cette poign\u00e9e de main orbitale en 1975, lorsque qu\u2019un module Soyouz s\u2019arrima \u00e0 une capsule Apollo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.blog.neoprog.eu\/index.php\/2021\/05\/05\/apollo-soyouz\/","og_locale":"fr_FR","og_type":"article","og_title":"Apollo-Soyouz - Le Blog du N\u00e9oprog","og_description":"Je me souviens parfaitement de cette poign\u00e9e de main orbitale en 1975, lorsque qu\u2019un module Soyouz s\u2019arrima \u00e0 une capsule Apollo.","og_url":"https:\/\/www.blog.neoprog.eu\/index.php\/2021\/05\/05\/apollo-soyouz\/","og_site_name":"Le Blog du N\u00e9oprog","article_published_time":"2021-05-05T05:00:00+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2021\/04\/apollo-soyouz.jpg","type":"image\/jpeg"}],"author":"Neoprog","twitter_card":"summary_large_image","twitter_creator":"@Le_Brun_JC","twitter_site":"@Le_Brun_JC","twitter_misc":{"\u00c9crit par":"Neoprog","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2021\/05\/05\/apollo-soyouz\/#article","isPartOf":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2021\/05\/05\/apollo-soyouz\/"},"author":{"name":"Neoprog","@id":"https:\/\/www.blog.neoprog.eu\/#\/schema\/person\/47c594bf12736b172b772f0f02bcf511"},"headline":"Apollo-Soyouz","datePublished":"2021-05-05T05:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2021\/05\/05\/apollo-soyouz\/"},"wordCount":321,"commentCount":0,"publisher":{"@id":"https:\/\/www.blog.neoprog.eu\/#\/schema\/person\/47c594bf12736b172b772f0f02bcf511"},"image":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2021\/05\/05\/apollo-soyouz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2021\/04\/apollo-soyouz.jpg","keywords":["Apollo-Soyouz","espace","For All Mankind","guerre froide","lune","S\u00e9rie TV"],"articleSection":["Apple","science-fiction","S\u00e9ries TV"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.blog.neoprog.eu\/index.php\/2021\/05\/05\/apollo-soyouz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2021\/05\/05\/apollo-soyouz\/","url":"https:\/\/www.blog.neoprog.eu\/index.php\/2021\/05\/05\/apollo-soyouz\/","name":"Apollo-Soyouz - Le Blog du N\u00e9oprog","isPartOf":{"@id":"https:\/\/www.blog.neoprog.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2021\/05\/05\/apollo-soyouz\/#primaryimage"},"image":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2021\/05\/05\/apollo-soyouz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2021\/04\/apollo-soyouz.jpg","datePublished":"2021-05-05T05:00:00+00:00","description":"Je me souviens parfaitement de cette poign\u00e9e de main orbitale en 1975, lorsque qu\u2019un module Soyouz s\u2019arrima \u00e0 une capsule Apollo.","breadcrumb":{"@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2021\/05\/05\/apollo-soyouz\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blog.neoprog.eu\/index.php\/2021\/05\/05\/apollo-soyouz\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2021\/05\/05\/apollo-soyouz\/#primaryimage","url":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2021\/04\/apollo-soyouz.jpg","contentUrl":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2021\/04\/apollo-soyouz.jpg","width":1024,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/www.blog.neoprog.eu\/index.php\/2021\/05\/05\/apollo-soyouz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.blog.neoprog.eu\/"},{"@type":"ListItem","position":2,"name":"Apollo-Soyouz"}]},{"@type":"WebSite","@id":"https:\/\/www.blog.neoprog.eu\/#website","url":"https:\/\/www.blog.neoprog.eu\/","name":"Le Blog du N\u00e9oprog","description":"","publisher":{"@id":"https:\/\/www.blog.neoprog.eu\/#\/schema\/person\/47c594bf12736b172b772f0f02bcf511"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blog.neoprog.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.blog.neoprog.eu\/#\/schema\/person\/47c594bf12736b172b772f0f02bcf511","name":"Neoprog","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2022\/09\/autoportrait-2.jpg","url":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2022\/09\/autoportrait-2.jpg","contentUrl":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2022\/09\/autoportrait-2.jpg","width":1024,"height":681,"caption":"Neoprog"},"logo":{"@id":"https:\/\/www.blog.neoprog.eu\/wp-content\/uploads\/2022\/09\/autoportrait-2.jpg"}}]}},"_links":{"self":[{"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/posts\/6848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/comments?post=6848"}],"version-history":[{"count":1,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/posts\/6848\/revisions"}],"predecessor-version":[{"id":6850,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/posts\/6848\/revisions\/6850"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/media\/6849"}],"wp:attachment":[{"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/media?parent=6848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/categories?post=6848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blog.neoprog.eu\/index.php\/wp-json\/wp\/v2\/tags?post=6848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}